{"id":5701,"date":"2024-10-22T12:57:26","date_gmt":"2024-10-22T10:57:26","guid":{"rendered":"https:\/\/www.lasallefoundation.org\/?post_type=avada_portfolio&#038;p=5701"},"modified":"2024-10-22T13:11:28","modified_gmt":"2024-10-22T11:11:28","slug":"la-salle-pouthum-educazione-per-bambini-irregolari","status":"publish","type":"avada_portfolio","link":"https:\/\/www.lasallefoundation.org\/it\/project\/la-salle-pouthum-educazione-per-bambini-irregolari\/","title":{"rendered":"Istruzione per Bambini Apolidi in Cambogia"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-1\"><h2><span style=\"font-weight: 400;\">La Salle Pouthum si dedica a promuovere l&#8217;accesso all&#8217;istruzione e alla cittadinanza per i bambini apolidi senza documenti originari del Vietnam.<\/span><\/h2>\n<\/div><div style=\"text-align:right;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:30px;--awb-margin-bottom:60px;\" target=\"_self\" href=\"https:\/\/dona.1lasalle.lasallefoundation.org\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Sostieni il progetto<\/span><\/a><\/div><div class=\"fusion-text fusion-text-2\"><p>Nelle vicinanze della scuola La Salle Pouthum in Cambogia, vivono famiglie vulnerabili di rifugiati vietnamiti che affrontano sfide significative. Tra le difficolt\u00e0 pi\u00f9 gravi vi \u00e8 la mancanza di documenti e certificati di nascita per i loro figli, che rende questi bambini apolidi e impedisce loro di accedere all&#8217;istruzione. Queste famiglie sono costrette a vivere sull&#8217;acqua, l&#8217;unico luogo considerato terra di nessuno, dove vivono in condizioni di estrema povert\u00e0.<\/p>\n<p>La nostra scuola La Salle Pouthum vuole sostenere oltre 70 alunni provenienti da tre villaggi, coprendo i costi di trasporto per gli studenti provenienti da villaggi remoti e un pasto al giorno.<\/p>\n<p>Per risolvere queste problematiche, la scuola ha urgente bisogno di fondi per coprire le spese di viaggio degli studenti, i materiali didattici e il cibo.<\/p>\n<h4 style=\"text-align: center;\"><span style=\"font-weight: 400;\">Scegli quanto vuoi donare cliccando sulla parola <\/span><a href=\"https:\/\/dona.1lasalle.lasallefoundation.org\/\" target=\"_blank\" rel=\"noopener\"><b>DONA<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/h4>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"768\" title=\"Vietnamese Migrants in Cambodia (17)\" src=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17.jpg\" data-orig-src=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-1024x768.jpg\" alt class=\"lazyload img-responsive wp-image-5705\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271920%27%20viewBox%3D%270%200%202560%201920%27%3E%3Crect%20width%3D%272560%27%20height%3D%271920%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-200x150.jpg 200w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-400x300.jpg 400w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-600x450.jpg 600w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-800x600.jpg 800w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/Vietnamese-Migrants-in-Cambodia-17-1200x900.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 700px) 100vw, 1200px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-3\"><p><span style=\"font-weight: 400;\">Questo progetto non solo sostiene i bambini cambogiani locali, ma fornisce anche un aiuto vitale ai bambini vietnamiti emarginati in Cambogia, dando loro speranza e creando opportunit\u00e0 per un futuro migliore<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continuiamo a sostenere i nostri studenti di La Salle Pothum; loro e noi siamo parte della famiglia <\/span><b>#1LaSalle<\/b><span style=\"font-weight: 400;\">. Facciamo in modo che i nostri progetti realizzino i sogni di sempre pi\u00f9 bambini attraverso la scuola. Ogni donazione ci aiuta a continuare la nostra missione.<\/span><\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><img decoding=\"async\" width=\"1024\" height=\"768\" title=\"la-salle-pouthum-3\" src=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3.jpg\" data-orig-src=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-1024x768.jpg\" alt class=\"lazyload img-responsive wp-image-5709\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%272560%27%20height%3D%271920%27%20viewBox%3D%270%200%202560%201920%27%3E%3Crect%20width%3D%272560%27%20height%3D%271920%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-200x150.jpg 200w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-400x300.jpg 400w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-600x450.jpg 600w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-800x600.jpg 800w, https:\/\/www.lasallefoundation.org\/wp-content\/uploads\/2024\/10\/la-salle-pouthum-3-1200x900.jpg 1200w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 700px) 100vw, 1200px\" \/><\/span><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:40px;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-4\"><p><b>In La Salle Foundation, lavoriamo per creare un mondo in cui l&#8217;istruzione sia accessibile a tutti i bambini. E tu, che mondo scegli?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Scopri di pi\u00f9 su altri progetti educativi supportati da La Salle Foundation:<\/span><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Foyer Akwaba in Costa d&#8217;Avorio, Africa<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Zona Reina in Guatemala, America<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Fratelli Project in Libano, Asia<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":5737,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"portfolio_category":[],"portfolio_skills":[],"portfolio_tags":[102,101],"class_list":["post-5701","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_tags-1lasalle","portfolio_tags-parc"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/avada_portfolio\/5701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/comments?post=5701"}],"version-history":[{"count":6,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/avada_portfolio\/5701\/revisions"}],"predecessor-version":[{"id":5741,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/avada_portfolio\/5701\/revisions\/5741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/media\/5737"}],"wp:attachment":[{"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/media?parent=5701"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/portfolio_category?post=5701"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/portfolio_skills?post=5701"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.lasallefoundation.org\/it\/wp-json\/wp\/v2\/portfolio_tags?post=5701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}